{"id":5310,"date":"2019-11-26T08:38:29","date_gmt":"2019-11-26T07:38:29","guid":{"rendered":"https:\/\/www.bridal-times.com\/de\/?p=5310"},"modified":"2020-08-12T20:26:54","modified_gmt":"2020-08-12T18:26:54","slug":"preview-gallery-fashion-januar-2020","status":"publish","type":"post","link":"https:\/\/www.bridal-times.com\/de\/preview-gallery-fashion-januar-2020\/","title":{"rendered":"Preview &#8222;Gallery Fashion&#8220; Januar 2020 in D\u00fcsseldorf"},"content":{"rendered":"<blockquote><p>Etabliert, gesch\u00e4tzt und innovativ \u2013 das ist die Gallery FASHION, die internationale Fashion Trade Show der Igedo Company. Das Areal B\u00f6hler als Location f\u00fcr die Order-Plattform in D\u00fcsseldorf bietet die M\u00f6glichkeit alle Segmente \u2013 Agencies und Premium Brands, Contemporary, Design und Avantgarde, Accessories und Shoes sowie Evening &amp; Occasion \u2013 an einem Ort zur gleichen Zeit darzustellen.<\/p><\/blockquote>\n<p>Mit Auftakt der neuen Saison pr\u00e4sentiert sich die D\u00fcsseldorfer Modeplattform mit neuem komplettierten Logo: Statt Gallery wird sie k\u00fcnftig mit \u201aGallery FASHION\u2018 als stimmiges Pendant zur Schwestermesse \u201aGallery SHOES\u2018 auf dem Markt pr\u00e4sent sein.<\/p>\n<p><strong>NEUES LOGO F\u00dcR GEBALLTE POWER<\/strong><\/p>\n<p>\u201eDas ist nicht nur eine stilistische Angelegenheit, sondern auch eine klare Botschaft an den Markt: Heute stehen diese beiden Messen fest gesetzt und sich erg\u00e4nzend nebeneinander\u201c, fasst Ulrike K\u00e4hler, Managing Director Igedo Company und Project Director beider Formate, zusammen. \u201eGallery FASHION hat das gleiche Potential wie Gallery SHOES. Auch, was eine vollst\u00e4ndige Auslastung des Areal B\u00f6hler mit m\u00f6glichen zus\u00e4tzlichen drei Leichtbau-Hallen angeht. In dieser Zeit vieler Umbr\u00fcche und Ver\u00e4nderungen bieten wir mit unseren zeitgem\u00e4\u00dfen, praktischen und effizienten Konzepten tragende Stabilit\u00e4t.<\/p>\n<p>Das gr\u00f6\u00dfte Wachstum wird im SHOWROOM CONCEPT angestrebt. \u201eDieser mittlerweile l\u00e4ngst etablierte und magnetische Ansatz schl\u00e4gt immer gr\u00f6\u00dfere Wellen. Zur kommenden Ausgabe werden wir das SHOWROOM CONCEPT explizit mit einem spezifischen Panel-Talk in Zusammenarbeit mit Branchengr\u00f6\u00dfen im Rahmenprogramm unterst\u00fctzen\u201c, so Ulrike K\u00e4hler weiterhin.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5312 aligncenter\" src=\"https:\/\/www.bridal-times.com\/de\/wp-content\/uploads\/2019\/11\/Gallery_I_2020_presenter_600x600_V1.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.bridal-times.com\/de\/wp-content\/uploads\/2019\/11\/Gallery_I_2020_presenter_600x600_V1.jpg 600w, https:\/\/www.bridal-times.com\/de\/wp-content\/uploads\/2019\/11\/Gallery_I_2020_presenter_600x600_V1-300x300.jpg 300w, https:\/\/www.bridal-times.com\/de\/wp-content\/uploads\/2019\/11\/Gallery_I_2020_presenter_600x600_V1-150x150.jpg 150w, https:\/\/www.bridal-times.com\/de\/wp-content\/uploads\/2019\/11\/Gallery_I_2020_presenter_600x600_V1-520x520.jpg 520w, https:\/\/www.bridal-times.com\/de\/wp-content\/uploads\/2019\/11\/Gallery_I_2020_presenter_600x600_V1-50x50.jpg 50w, https:\/\/www.bridal-times.com\/de\/wp-content\/uploads\/2019\/11\/Gallery_I_2020_presenter_600x600_V1-500x500.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>SHOWROOM CONCEPT<\/strong><\/p>\n<p>Was vor acht Saisons mit einem kleineren Teilbereich in einer Halle angefangen hat, ist mittlerweile zum Hotspot f\u00fcr internationale Top-Agenturen und hochwertige Brands geworden. Inzwischen umfasst das SHOWROOM CONCEPT drei ganze Hallen, in denen f\u00fcnf bis teils sogar zehn Tage lang reges Business herrscht.<\/p>\n<p>Das Konzept ist eine smarte, tempor\u00e4re Alternative zu l\u00e4ngerfristig angemieteten Showrooms, die es Facheink\u00e4ufern und Ausstellern erm\u00f6glicht, komprimiert zu arbeiten und gleichzeitig Kosten, Aufwand und Zeit zu sparen. Neben dem eigenen Termingesch\u00e4ft profitiert das SHOWROOM CONCEPT zudem von Fachbesuchern, die die urspr\u00fcngliche dreit\u00e4gige Kernveranstaltung Gallery FASHION besuchen. Alles in allem eine optimale Orderatmosph\u00e4re f\u00fcr effizientes Arbeiten in einer szenigen Industrielocation mit stimmiger Nachbarschaft und Shuttle-Service.<\/p>\n<p><strong>SIDE EVENTS<\/strong><\/p>\n<p>Ein fachlich fundiertes Rahmenprogramm mit ausgew\u00e4hlten Side Events rundet das Angebot der Gallery FASHION ab. Neben aufmerksamkeitsstarken Kollektionspr\u00e4sentationen, Panel-Talks und Vortr\u00e4gen sowie einer Trend-Area, die in \u201aAlte Schmiedehallen\u2018 Inspirationen f\u00fcr Shopgestaltung gibt, ist Gallery FASHION TRENDVIEW erneut als zentrale Orderinformation f\u00fcr die kommende Saison geplant.<\/p>\n<p>Trendexpertin Karolina Landowski von Fashion Trend Pool und Igedo Fashion Director Alexander Radermacher referieren \u00fcber die wichtigsten Orderthemen der Womens- und Menswear: Welche Keylooks werden die Saison Herbst\/Winter 2020\/21 bestimmen und welche Must-haves sind bei der Order unverzichtbar? Save the Date: Sonntag, 26. Januar 2020 um 10:30 Uhr auf dem Areal B\u00f6hler in ,Alte Schmiedehallen\u2018.<\/p>\n<p>Weitere Informationen zum Rahmenprogramm folgen in K\u00fcrze.<\/p>\n<p><strong>\u201aNEW ARRIVALS\u2018 IN \u201aALTE SCHMIEDEHALLEN\u2018- DER ZENTRALEN PLATTFORM F\u00dcR INTERNATIONALE MARKENSEGMENTE<\/strong><\/p>\n<p>Mit dreit\u00e4giger Kernlaufzeit vom <strong>25. bis 27. Januar 2020<\/strong> bieten \u201aAlte Schmiedehallen\u2018 als zentrale Plattform r\u00e4umliche Teilbereiche f\u00fcr die drei Segmente Avantgarde, Design &amp; Contemporary, Accessories &amp; Shoes sowie Evening &amp; Occasion an.<\/p>\n<p>Zu den neuen Brands aus dem Bereich Avantgarde, Design &amp; Contemporary geh\u00f6ren u.a. hochwertig Zeitloses von ALGO of Switzerland mit \u00fcber 100-j\u00e4hriger Familientradition, 1917 in der Schweiz gegr\u00fcndet. Aus Polen kommt das seit 2011 existierende Brand RISK made in Warsaw: Produziert wird in Europa, gen\u00e4ht ausschlie\u00dflich im eigenen Land. Aus den Niederlanden zeigen hochwertige, modische Supersize-Kollektionen von Yoek Flagge. Nachhaltig, klassisch und langlebig: Muse Knitwear von einem d\u00e4nischen Designunternehmen in Familienhand, umgeben von der wilden Sch\u00f6nheit der Nordsee und des Nationalparks Thy. LauriJarvinenStudio aus Finnland steht f\u00fcr nordisch-minimalistische Avantgarde mit modernem Twist.<\/p>\n<p>Neu im Segment Accessories &amp; Shoes sind Western-Accessories wie G\u00fcrtel und H\u00fcte von Stars &amp; Stripes aus Deutschland. Aus den Niederlanden sind Schuhe von Scotch &amp; Soda sowie State of Brands mit einer Schmuckkollektion dabei. Traditionell stark in der Wintersaison sind M\u00fctzen, H\u00fcte und Caps mit Neuausstellern wie Adolf Nytra \u2013 Anytra aus Tschechien, Dasmarca Hat Company aus Gro\u00dfbritannien, handgefertigte H\u00fcte von Marone aus Italien oder Kappen von Rabionek aus Polen. Deutsches Heimspiel f\u00fcr hochwertige Filzh\u00fcte von Kastori oder H\u00fcte und Accessoires von BEDACHT, Kopka, Fiebig, Alfonso d`Este und Qui Nous.<\/p>\n<p>Evening &amp; Occasion zeigt neu neben wichtigen internationalen Key Playern wie Christian Koehlert, Gina Bacconi, Luxuar und Fashion New York sowie das polnische Brand Marselini mit exklusiven Abend- und Cocktailkleidern.<\/p>\n<p><strong>\u201aWHO IS WHO\u2019 IM SHOWROOM CONCEPT- PREMIUM-BRANDS UND AGENTUREN<\/strong><\/p>\n<p>An mindestens f\u00fcnf Tagen findet hier erweitertes Ordern in insgesamt drei Hallen mit authentischer Industriekulisse statt. Anzahl der Agenturen und Brands wie auch Agenturportfolios selbst wachsen kontinuierlich.<\/p>\n<p>In der Kaltstahlhalle sind aus Deutschland erneut dabei: 04651 aus dem Hause BRAUN Hamburg, A TRIP IN A BAG mit feinster Damenmode, Brasi &amp; Brasi mit Fashion und Bags, Edelle by Edward Copper u.a. mit Blusen, Hemden, Kleidern und Accessoires. Hugenberg zeigt Strick, Joana Danciu Kleider und R\u00f6cke, Seldom Strickmanufaktur Knit und neu Ralph Gladen handgefertigte G\u00fcrtel und Leder-Accessoires. Oder: Le Temps de Cerises aus Frankreich mit Fashion. Schuhe und Accessoires von Lottusse 1877 und Shoto aus Italien. Neu: die Jacken von Mehran Srl und M\u00e4ntel der italienischen Brands Ekoluk und Tavus Milano.<\/p>\n<p>Im Agenturbereich der Kaltstahlhalle haben zahlreiche Brand-Repr\u00e4sentanten bereits zu diesem fr\u00fchen Zeitpunkt ihre Teilnahme best\u00e4tigt: 22FASHION AGENCY, AGENTUR STEFAN KUDLA \u2013 THE LAST OF THE TRUE und Moderaum Fischer. Zu den Wiederkehrern geh\u00f6ren zudem HERITAGE AGENTS mit den Brands Circolo 1901 und WarmMe. Claudio Parolini, der ehemalige Europalizenznehmer von Gilded Age, stellt mit seiner Made-in-Italy-M\u00e4nnerjeans The Nim Standard eine neue aufstrebende Premiummarke aus dem Denim-Bereich vor. Showroom Gabi Heininger zeigt Inuikii aus Deutschland, M\u00e9lin\u00e9, Numero 10 Bags sowie Officine Creative aus Italien und Zesp\u00e0 aus dem franz\u00f6sischen Aix-en-Provence. MODEAGENTUR MINDNER bringt die britischen Brands Madeleine Thomson und Star Mel als auch Nomads aus den USA und Graumann aus D\u00e4nemark mit. NEU: Fair-Fashion-Smartphone-Necklaces von studioNOOKS, Made in Germany.<\/p>\n<p>Markenvielfalt von DIE Hinterhofagentur: Blune, Des Petit Hauts und Leon &amp; Harper aus Frankreich. Ad Hoc, BOB, Cape Horn, Manuel Ritz, Original Vintage Style, Portofiori, Taylor Tweed und Wool &amp; Co aus Italien. Koike Barcelona aus Spanien. 8 and 7 aus Deutschland. Lightning Bolt aus den USA sowie The Jacksons aus Gro\u00dfbritannien. Neu und italienisch die DOB von Good Match. CELINE KLAUSER FASHION AGENCY zeigt AGG\u00c9L und V+R aus Griechenland, Cat Noir aus Deutschland, KAOS aus Italien und Lauren Moshi aus den USA. Neuzugang aus Spanien mit eigenen Shops in Madrid und Los Angeles: The extreme collection. Ein Brand, das seit 30 Jahren im Familienbetrieb nachhaltig und in limitierter Auflage produziert. KNALLGRAU\/AGENTUR F\u00dcR MODE auf erweiterter Fl\u00e4che mit Doo-Wop, FLOOR Clothing, RO\u2019Skinwear und SHIRTAPORTER aus Italien, WUTH Cashmere aus D\u00e4nemark sowie weiteren neuen Brands wie Magnolya Kleiderkollektion aus Spanien und der in Deutschland ans\u00e4ssigen und produzierten Premium-Kollektion aus Kaschmir von Villa Gaia by Romy Staib. Erneut belegt von Agentur Klauser: Halle am Wasserturm mit \u201anew entries\u2018 wie Aquascutum mit innovativer, britischer Handwerkskunst seit 1859 oder handgeflochtene Ledertaschen und G\u00fcrtel aus Belgien von Dragon Diffusion. Aus Frankreich: Les Tricots de L\u00e9a mit einer frischen, femininen Kollektion, Pr\u00eat-\u00e0-porter von Stella Forest und feinste Naturlederprodukte aus Paris von Ventcouvert. Zudem Mens- und Womenswear aus den USA von Manrico Cashmere, italienische Herrenmode von Maurizio Miri, Lederwaren im unisex-used Look von Mino Ronzoni 1953, Hev\u00f3 mit einer Damenkollektion oder luxuri\u00f6ser Strick von Lunaria Cashmere, beides ebenfalls aus Italien.<\/p>\n<p>F\u00fcr weitere Informationen \u00fcber die Fashion Trade Show in D\u00fcsseldfor, besuchen Sie <a href=\"https:\/\/gallery-duesseldorf.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gallery Fashion<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Etabliert, gesch\u00e4tzt und innovativ \u2013 das ist die Gallery FASHION, die internationale Fashion Trade Show der Igedo Company. Das Areal B\u00f6hler als Location f\u00fcr die Order-Plattform in D\u00fcsseldorf bietet die M\u00f6glichkeit alle Segmente \u2013 Agencies und Premium Brands, Contemporary, Design und Avantgarde, Accessories und Shoes sowie Evening &amp; Occasion \u2013 an einem Ort zur gleichen Zeit darzustellen. Mit Auftakt der neuen Saison pr\u00e4sentiert sich die D\u00fcsseldorfer Modeplattform mit neuem komplettierten Logo: Statt Gallery wird sie k\u00fcnftig mit \u201aGallery FASHION\u2018 als stimmiges Pendant zur Schwestermesse \u201aGallery SHOES\u2018 auf dem Markt pr\u00e4sent sein. NEUES LOGO F\u00dcR GEBALLTE POWER \u201eDas ist nicht nur eine stilistische Angelegenheit, sondern auch eine klare Botschaft an den Markt: Heute stehen diese beiden Messen fest gesetzt und sich erg\u00e4nzend nebeneinander\u201c, fasst Ulrike K\u00e4hler, Managing Director Igedo Company und Project Director beider Formate, zusammen. \u201eGallery FASHION hat das gleiche Potential wie Gallery SHOES. Auch, was eine vollst\u00e4ndige Auslastung des Areal B\u00f6hler mit m\u00f6glichen zus\u00e4tzlichen drei Leichtbau-Hallen angeht. In dieser Zeit vieler Umbr\u00fcche und Ver\u00e4nderungen bieten wir mit unseren zeitgem\u00e4\u00dfen, praktischen und effizienten Konzepten tragende Stabilit\u00e4t. Das gr\u00f6\u00dfte Wachstum wird im SHOWROOM CONCEPT angestrebt. \u201eDieser mittlerweile l\u00e4ngst etablierte und magnetische Ansatz schl\u00e4gt immer gr\u00f6\u00dfere Wellen. Zur kommenden Ausgabe werden wir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5322,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[20,62],"tags":[],"class_list":["post-5310","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-haendler-news","category-top-news","post_format-post-format-video"],"_links":{"self":[{"href":"https:\/\/www.bridal-times.com\/de\/wp-json\/wp\/v2\/posts\/5310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bridal-times.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bridal-times.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bridal-times.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bridal-times.com\/de\/wp-json\/wp\/v2\/comments?post=5310"}],"version-history":[{"count":8,"href":"https:\/\/www.bridal-times.com\/de\/wp-json\/wp\/v2\/posts\/5310\/revisions"}],"predecessor-version":[{"id":5325,"href":"https:\/\/www.bridal-times.com\/de\/wp-json\/wp\/v2\/posts\/5310\/revisions\/5325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bridal-times.com\/de\/wp-json\/wp\/v2\/media\/5322"}],"wp:attachment":[{"href":"https:\/\/www.bridal-times.com\/de\/wp-json\/wp\/v2\/media?parent=5310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bridal-times.com\/de\/wp-json\/wp\/v2\/categories?post=5310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bridal-times.com\/de\/wp-json\/wp\/v2\/tags?post=5310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}